{"id":8341,"date":"2024-08-04T19:58:06","date_gmt":"2024-08-04T17:58:06","guid":{"rendered":"https:\/\/ruth23weber.de\/blog\/?p=8341"},"modified":"2024-08-04T20:00:32","modified_gmt":"2024-08-04T18:00:32","slug":"leuchten-am-rhein","status":"publish","type":"post","link":"https:\/\/ruth23weber.de\/blog\/leuchten-am-rhein\/","title":{"rendered":"Leuchten am Rhein"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-8339\" src=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/08\/024Labradoritfisch-700x933.jpg\" alt=\"\" width=\"700\" height=\"933\" srcset=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/08\/024Labradoritfisch-700x933.jpg 700w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/08\/024Labradoritfisch-225x300.jpg 225w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/08\/024Labradoritfisch-768x1024.jpg 768w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/08\/024Labradoritfisch-800x1067.jpg 800w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/08\/024Labradoritfisch.jpg 1125w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><br \/>\nWir fahren auf der alten Landstra\u00dfe vorbei an \u00fcppigen B\u00e4umen und reifen Feldern. Am Rand die Wegwarten himmelblau, dazwischen Habichtskraut, Ackersenf und Rainfarn \u2013 goldgelbe Sonnenflecken. Der Himmel war seit Tagen schon grau und grau, aber es regnet heute nicht. Das ist heimatlich und familiengleich. Das kenne ich. Solche Sommer kenne ich. Es wuchert und w\u00e4chst. Auf dem Friedhof streiten wir ein wenig. Rupf ich das Efeu ab und lasse den Huflattich stehen? Ich werfe beides auf den Kompost. Sechs Sommer ohne die Eltern, die die Namen \u2013 besonders die Mutter \u2013 der Pflanzen kannten.<br \/>\nIm Nachbardorf setzen wir uns in den Wirtshausgarten hinter der kleinen Kirche. Von hier aus k\u00f6nnen wir den Rhein sehen. Die Wirtin im wei\u00dfen Kittel gr\u00fc\u00dft knapp mit einem L\u00e4cheln. Der gro\u00dfe alte Kellner muss sich unter den Platanen b\u00fccken, als er uns die Speisen und das Glas Riesling bringt. Eine M\u00fccke l\u00e4sst sich auf meinem Oberarm nieder und will durch die Wolljacke stechen. Ich bemerke aber rechtzeitig einen winzigen Schmerz und jage sie fort, bevor sie an mein Blut kommt. Wir schauen uns an und lassen uns hier Zeit, bestellen sogar noch Apfelkuchen, Erdbeeren, Sahne und Eis zum Nachtisch.<\/p>\n<h5><em>Das Geburtstagsgeschenk, ein geschnitzter, chinesischer Karpfen aus Labradorit auf glaublauem Achat und Chalzedon, Sammlung RW, Fotografie RW 3\/4. 8. 2024<\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Wir fahren auf der alten Landstra\u00dfe vorbei an \u00fcppigen B\u00e4umen und reifen Feldern. Am Rand die Wegwarten himmelblau, dazwischen Habichtskraut, Ackersenf und Rainfarn \u2013 goldgelbe Sonnenflecken. Der Himmel war seit Tagen schon grau und grau, aber es regnet heute nicht. Das ist heimatlich und familiengleich. Das kenne ich. Solche Sommer kenne ich. Es wuchert und&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,5,15,6,4],"tags":[],"_links":{"self":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts\/8341"}],"collection":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/comments?post=8341"}],"version-history":[{"count":4,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts\/8341\/revisions"}],"predecessor-version":[{"id":8345,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts\/8341\/revisions\/8345"}],"wp:attachment":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/media?parent=8341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/categories?post=8341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/tags?post=8341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}