{"id":8298,"date":"2024-06-18T18:06:16","date_gmt":"2024-06-18T16:06:16","guid":{"rendered":"https:\/\/ruth23weber.de\/blog\/?p=8298"},"modified":"2024-06-18T18:10:18","modified_gmt":"2024-06-18T16:10:18","slug":"auf-dem-bauch-des-tigers","status":"publish","type":"post","link":"https:\/\/ruth23weber.de\/blog\/auf-dem-bauch-des-tigers\/","title":{"rendered":"Auf dem Bauch des Tigers"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-large wp-image-8299\" src=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/06\/024JapanischerGarten-700x933.jpg\" alt=\"\" width=\"700\" height=\"933\" srcset=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/06\/024JapanischerGarten-700x933.jpg 700w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/06\/024JapanischerGarten-225x300.jpg 225w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/06\/024JapanischerGarten-768x1024.jpg 768w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/06\/024JapanischerGarten-800x1067.jpg 800w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2024\/06\/024JapanischerGarten.jpg 1125w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>Diese sch\u00f6ne Geschichte wollte ich schon seit ein paar Tagen erz\u00e4hlen. In einem gro\u00dfen Gartengel\u00e4nde mit einem dunklen flie\u00dfenden Wasser, braunen, aber bewachsenen Ufern gehe ich auf und ab. Unter B\u00e4umen und B\u00fcschen, auch hohen Stauden. Dort weiden Tiere, Ziegen und Schafe mit gedrehten H\u00f6rnern und hellbraunem Fell. Gro\u00dfe Tiger sind ebenso dort, aber in ferneren Bereichen. Ich habe Angst, dass sie n\u00e4her kommen. Die Tiger sind hell und tr\u00e4ge. Dann sehe ich einen kleinen Tiger an meinem Ufer. Er kommt auf mich zu, wie eine Katze streicht er Runde um Runde. Ich fasse Zutrauen und ber\u00fchre sein Fell mit einem spitzen \u00c4stchen. Er scheint es zu m\u00f6gen und so kraule ich ihn mutig mit der blo\u00dfen Hand. Das Fell f\u00fchlt sich rau und gefettet an. Der kleine Tiger spricht oder deutet, wie er gekrault werden m\u00f6chte. Er geht dann ins morastige Wasser, taucht wieder auf und legt sich in einiger Entfernung auf den R\u00fccken. Ob er auch auf dem Bauch gekrault werden will? Das Bauchfell ist aschwei\u00df und ich sehe darauf viele bunte Edelsteine in hellen Farben leuchten, die das Tier im Wasser aufgefunden hat. Sie blieben beim Auftauchen im Fell haften. Er deutet an, dass wir (meine Schwester ist pl\u00f6tzlich auch hier am Flu\u00df) davon nehmen d\u00fcrfen, soviel wir wollen. Das Edelsteinsammeln ist hier im Land verboten, wie ich wei\u00df. Die einzige Ausnahme ist jedoch das Klauben vom Bauch eines Tigers. Ich betrachte die Steine genauer. Es sind Turmaline von Gr\u00fcn bis Rosa, klare Bergkristalle und taubenblutrote Rubine. Ich verstecke meine Ausbeute in der Kleidung. Meine Schwester hat nur drei Steine in ihrer Handfl\u00e4che \u2013 eine dunkelgr\u00fcne Turmalinnadel mit Zwillingskristall, einen Rubin und eine Quarznadel. Das Bild ist mir noch so deutlich vor Augen.<\/p>\n<h5><em>Im japanischen Garten D\u00fcsseldorf, digital bearbeitete Fotografie RW Mai 2024<\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Diese sch\u00f6ne Geschichte wollte ich schon seit ein paar Tagen erz\u00e4hlen. In einem gro\u00dfen Gartengel\u00e4nde mit einem dunklen flie\u00dfenden Wasser, braunen, aber bewachsenen Ufern gehe ich auf und ab. Unter B\u00e4umen und B\u00fcschen, auch hohen Stauden. Dort weiden Tiere, Ziegen und Schafe mit gedrehten H\u00f6rnern und hellbraunem Fell. Gro\u00dfe Tiger sind ebenso dort, aber in&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,5,4,17],"tags":[],"_links":{"self":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts\/8298"}],"collection":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/comments?post=8298"}],"version-history":[{"count":4,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts\/8298\/revisions"}],"predecessor-version":[{"id":8303,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts\/8298\/revisions\/8303"}],"wp:attachment":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/media?parent=8298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/categories?post=8298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/tags?post=8298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}