{"id":2860,"date":"2019-03-17T07:57:48","date_gmt":"2019-03-17T06:57:48","guid":{"rendered":"http:\/\/ruth23weber.de\/blog\/?p=2860"},"modified":"2019-03-17T08:45:27","modified_gmt":"2019-03-17T07:45:27","slug":"__trashed-3__trashed","status":"publish","type":"post","link":"https:\/\/ruth23weber.de\/blog\/__trashed-3__trashed\/","title":{"rendered":"Korrespondenzen XXIX"},"content":{"rendered":"<p><a href=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/019TellerKangxi.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-2862\" src=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/019TellerKangxi-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/019TellerKangxi-225x300.jpg 225w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/019TellerKangxi-768x1024.jpg 768w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/019TellerKangxi-700x933.jpg 700w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/019TellerKangxi-800x1067.jpg 800w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/019TellerKangxi.jpg 1125w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><a href=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/018Tulpe.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-2863\" src=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/018Tulpe-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/018Tulpe-225x300.jpg 225w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/018Tulpe-768x1024.jpg 768w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/018Tulpe-700x933.jpg 700w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/018Tulpe-800x1067.jpg 800w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2019\/03\/018Tulpe.jpg 1125w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-399\" src=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2018\/03\/trennlinie_transparent.png\" width=\"800\" height=\"1\" srcset=\"https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2018\/03\/trennlinie_transparent.png 800w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2018\/03\/trennlinie_transparent-150x1.png 150w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2018\/03\/trennlinie_transparent-300x1.png 300w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2018\/03\/trennlinie_transparent-768x1.png 768w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2018\/03\/trennlinie_transparent-700x1.png 700w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2018\/03\/trennlinie_transparent-482x1.png 482w, https:\/\/ruth23weber.de\/blog\/wp-content\/uploads\/2018\/03\/trennlinie_transparent-80x1.png 80w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>Blaue Sch\u00f6nheiten<br \/>\nMit Kobaltblau und einem feinen Pinsel hat der Porzellanmaler einen Vogel auf den Scherben aufgetragen. Er zeichnete unter den Schnabel einen Kringel in das Gefieder, f\u00fcr europ\u00e4ische Augen ein gro\u00dfes <strong>G<\/strong>. Umgeben von Chrysanthemen, Gr\u00e4sern und\u00a0 Bl\u00e4ttern sitzt der Vogel bei einem skelettierten Stein, der sich wie ein Bogen \u00f6ffnet. Der Bildausschnitt zeigt nicht die ganze Pracht des Tellers. Neben Chrysanthemen findet man noch andere Blumen, Kirschbl\u00fctenzweige, Felsen und Wasser. Der Porzellanmaler arbeitete vor circa dreihundert Jahren sicher und routiniert an dem Dekor, wie viele Teller an einem Tag er wohl bemalte? Vielleicht sogar in einer Manufaktur in <span id=\"Jingdezhen\" class=\"mw-headline\">Jingdezhen? Auf der R\u00fcckseite des Tellers hat er mittig ein sch\u00f6nes Schriftzeichen angebracht und noch weitere Blumenranken auf den Rand.<br \/>\nIm Rijksmuseum in Amsterdam finden sich zwei Fayence-Teller mit fast identischem Dekor, vereinfacht zwar, aber alle Motive sind da. Sie sind etwa zur gleichen Zeit (1685 &#8211; 1710), aber in Delft entstanden. Die Niederl\u00e4ndische Ostindien-Kompanie hatte mit ihren Schiffen die Porzellane aus China mitgebracht. Die Dekore wurden von den Delftern kopiert, aber auf Irdenware. Erst 1708 hat B\u00f6ttger das Porzellan in Dresden entwickelt. Die Chinesen kennen es schon mindestens zwei Jahrtausende.<br \/>\n<\/span><span id=\"Jingdezhen\" class=\"mw-headline\">Die Tulpe war einst ein exotisches Gew\u00e4chs aus dem Osmanischen Reich und sp\u00e4ter hat bekannterma\u00dfen der Handel mit ihrer Zwiebel in den Niederlanden des sogenannten Goldenen Zeitalters zu gro\u00dfen Turbulenzen gef\u00fchrt.<br \/>\nDie oben abgebildete Tulpe hat ihre Pollen wie ein kostbares Pigment auf dem Bl\u00fctenblatt ausgesch\u00fcttet. Vielleicht sollte man damit einmal malen.<br \/>\nF\u00fcr meinen Bruder <strong>G<\/strong>JMW, der in diesen Tagen Geburtstag feiert.<br \/>\n<\/span><\/p>\n<h5><em>Porzellan-Teller (Detail) mit blauer Unterglasurmalerei\u00a0 aus der Kangxi Zeit, Sammlung RW, <\/em><em>2019, erworben in der basedonart gallery, D\u00fcsseldorf<br \/>\nTulpe mit Pollen, invertierte Fotografie RW, 2018<\/em><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Blaue Sch\u00f6nheiten Mit Kobaltblau und einem feinen Pinsel hat der Porzellanmaler einen Vogel auf den Scherben aufgetragen. Er zeichnete unter den Schnabel einen Kringel in das Gefieder, f\u00fcr europ\u00e4ische Augen ein gro\u00dfes G. Umgeben von Chrysanthemen, Gr\u00e4sern und\u00a0 Bl\u00e4ttern sitzt der Vogel bei einem skelettierten Stein, der sich wie ein Bogen \u00f6ffnet. Der Bildausschnitt zeigt&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,5,14],"tags":[],"_links":{"self":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts\/2860"}],"collection":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/comments?post=2860"}],"version-history":[{"count":19,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts\/2860\/revisions"}],"predecessor-version":[{"id":2884,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/posts\/2860\/revisions\/2884"}],"wp:attachment":[{"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/media?parent=2860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/categories?post=2860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ruth23weber.de\/blog\/wp-json\/wp\/v2\/tags?post=2860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}